{"id":2962,"date":"2024-08-28T17:27:52","date_gmt":"2024-08-28T23:27:52","guid":{"rendered":"https:\/\/owcia.com\/home\/?p=2962"},"modified":"2024-08-28T17:28:01","modified_gmt":"2024-08-28T23:28:01","slug":"resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china","status":"publish","type":"post","link":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/","title":{"rendered":"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;El mi\u00e9rcoles de 28 de agosto, la Secretar\u00eda de Econom\u00eda public\u00f3 la resoluci\u00f3n final del procedimiento administrativo de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del inicio y solicitud de la investigaci\u00f3n antidumping:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El 27 de julio de 2023, se public\u00f3 en el DOF, la Clavos Nacionales M\u00e9xico, S.A. de C.V., en adelante Clavos M\u00e9xico, y Clavos Nacionales C.N., S.A. de C.V., en adelante Clavos C.N., o en conjunto las Solicitantes, solicitaron el inicio del procedimiento administrativo de investigaci\u00f3n por pr\u00e1cticas desleales de comercio internacional, en su modalidad de discriminaci\u00f3n de precios, sobre las importaciones de clavos de acero para concreto originarias de China.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 26 de septiembre de 2023, la Secretar\u00eda public\u00f3 en el DOF, la \u00abResoluci\u00f3n por la que se acepta la solicitud de parte interesada y se declara el inicio del procedimiento administrativo de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia\u00bb, mediante la cual fij\u00f3 como periodo de investigaci\u00f3n el comprendido del 1 de mayo de 2022 al 30 de abril de 2023 y como periodo de an\u00e1lisis de da\u00f1o el comprendido del 1 de mayo de 2020 al 30 de abril de 2023.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/Imagen-de-WhatsApp-2024-08-28-a-las-17.07.23_aeafd2ad-min.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"350\" src=\"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/Imagen-de-WhatsApp-2024-08-28-a-las-17.07.23_aeafd2ad-min.webp\" alt=\"\" class=\"wp-image-2964\" style=\"width:326px;height:auto\" srcset=\"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/Imagen-de-WhatsApp-2024-08-28-a-las-17.07.23_aeafd2ad-min.webp 576w, https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/Imagen-de-WhatsApp-2024-08-28-a-las-17.07.23_aeafd2ad-min-480x292.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 576px, 100vw\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La presente resoluci\u00f3n dicta lo siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se declara concluido el procedimiento administrativo de investigaci\u00f3n en materia de pr\u00e1cticas desleales de comercio internacional, en su modalidad de discriminaci\u00f3n de precios, en consecuencia, se impone una cuota compensatoria definitiva ad valorem de 31% a las importaciones de clavos de acero para concreto originarias de China que ingresan a trav\u00e9s de la fracci\u00f3n arancelaria 7317.00.99 de la TIGIE, o por cualquier otra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con fundamento en el art\u00edculo 87 de la LCE, las cuotas compensatorias se aplicar\u00e1n sobre el valor en aduana declarado en el pedimento correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los importadores que conforme a esta Resoluci\u00f3n deban pagar la cuota compensatoria definitiva, no estar\u00e1n obligados a su pago si comprueban que el pa\u00eds de origen de la mercanc\u00eda es distinto a China.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presente resoluci\u00f3n entrar\u00e1 en vigor el d\u00eda siguiente de su publicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a la naturaleza informativa del comunicado, los invitamos a consultar la publicaci\u00f3n oficial en <strong><a href=\"https:\/\/www.dof.gob.mx\/nota_detalle.php?codigo=5737486&amp;fecha=28\/08\/2024#gsc.tab=0\">Diario Oficial de la Federaci\u00f3n.<\/a><\/strong> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;El mi\u00e9rcoles de 28 de agosto, la Secretar\u00eda de Econom\u00eda public\u00f3 la resoluci\u00f3n final del procedimiento administrativo de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia. Del inicio y solicitud de la investigaci\u00f3n antidumping: &nbsp;El 27 de julio de 2023, se [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":2963,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"_joinchat":[],"footnotes":""},"categories":[2,1],"tags":[],"class_list":["post-2962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banners","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0 &#8226; Agencia Aduanal OWCIA<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0 &#8226; Agencia Aduanal OWCIA\" \/>\n<meta property=\"og:description\" content=\"&nbsp;El mi\u00e9rcoles de 28 de agosto, la Secretar\u00eda de Econom\u00eda public\u00f3 la resoluci\u00f3n final del procedimiento administrativo de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia. Del inicio y solicitud de la investigaci\u00f3n antidumping: &nbsp;El 27 de julio de 2023, se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia Aduanal OWCIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/onatewilly\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-28T23:27:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-28T23:28:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"O\u00f1ate Willy CIA S.C.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OWCIAMX\" \/>\n<meta name=\"twitter:site\" content=\"@OWCIAMX\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"O\u00f1ate Willy CIA S.C.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/\"},\"author\":{\"name\":\"O\u00f1ate Willy CIA S.C.\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#\\\/schema\\\/person\\\/888b2ab4896ec57d3727b33389d0d5c9\"},\"headline\":\"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0\",\"datePublished\":\"2024-08-28T23:27:52+00:00\",\"dateModified\":\"2024-08-28T23:28:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/\"},\"wordCount\":426,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp\",\"articleSection\":[\"Banners\",\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/\",\"name\":\"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0 &#8226; Agencia Aduanal OWCIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp\",\"datePublished\":\"2024-08-28T23:27:52+00:00\",\"dateModified\":\"2024-08-28T23:28:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/#primaryimage\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp\",\"contentUrl\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/owcia.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/\",\"name\":\"Agencia Aduanal OWCIA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/owcia.com\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#organization\",\"name\":\"O\u00f1ate Willy y CIA SC\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/logo01.png\",\"contentUrl\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/logo01.png\",\"width\":300,\"height\":126,\"caption\":\"O\u00f1ate Willy y CIA SC\"},\"image\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/onatewilly\\\/\",\"https:\\\/\\\/x.com\\\/OWCIAMX\",\"https:\\\/\\\/www.instagram.com\\\/owciamx\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/owcia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#\\\/schema\\\/person\\\/888b2ab4896ec57d3727b33389d0d5c9\",\"name\":\"O\u00f1ate Willy CIA S.C.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g\",\"caption\":\"O\u00f1ate Willy CIA S.C.\"},\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/author\\\/lorenzo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0 &#8226; Agencia Aduanal OWCIA","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0 &#8226; Agencia Aduanal OWCIA","og_description":"&nbsp;El mi\u00e9rcoles de 28 de agosto, la Secretar\u00eda de Econom\u00eda public\u00f3 la resoluci\u00f3n final del procedimiento administrativo de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia. Del inicio y solicitud de la investigaci\u00f3n antidumping: &nbsp;El 27 de julio de 2023, se [&hellip;]","og_url":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/","og_site_name":"Agencia Aduanal OWCIA","article_publisher":"https:\/\/www.facebook.com\/onatewilly\/","article_published_time":"2024-08-28T23:27:52+00:00","article_modified_time":"2024-08-28T23:28:01+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp","type":"image\/webp"}],"author":"O\u00f1ate Willy CIA S.C.","twitter_card":"summary_large_image","twitter_creator":"@OWCIAMX","twitter_site":"@OWCIAMX","twitter_misc":{"Escrito por":"O\u00f1ate Willy CIA S.C.","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/#article","isPartOf":{"@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/"},"author":{"name":"O\u00f1ate Willy CIA S.C.","@id":"https:\/\/owcia.com\/home\/#\/schema\/person\/888b2ab4896ec57d3727b33389d0d5c9"},"headline":"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0","datePublished":"2024-08-28T23:27:52+00:00","dateModified":"2024-08-28T23:28:01+00:00","mainEntityOfPage":{"@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/"},"wordCount":426,"commentCount":0,"publisher":{"@id":"https:\/\/owcia.com\/home\/#organization"},"image":{"@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/#primaryimage"},"thumbnailUrl":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp","articleSection":["Banners","Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/","url":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/","name":"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0 &#8226; Agencia Aduanal OWCIA","isPartOf":{"@id":"https:\/\/owcia.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/#primaryimage"},"image":{"@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/#primaryimage"},"thumbnailUrl":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp","datePublished":"2024-08-28T23:27:52+00:00","dateModified":"2024-08-28T23:28:01+00:00","breadcrumb":{"@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/#primaryimage","url":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp","contentUrl":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/08\/IMAGENES-BLOG-2024-08-28T170951.956-min-1.webp","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/owcia.com\/home\/resolucion-final-del-procedimiento-de-investigacion-antidumping-sobre-las-importaciones-de-clavos-de-acero-para-concreto-originarias-de-china\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/owcia.com\/home\/"},{"@type":"ListItem","position":2,"name":"Resoluci\u00f3n final del procedimiento de investigaci\u00f3n antidumping sobre las importaciones de clavos de acero para concreto originarias de china\u00a0\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/owcia.com\/home\/#website","url":"https:\/\/owcia.com\/home\/","name":"Agencia Aduanal OWCIA","description":"","publisher":{"@id":"https:\/\/owcia.com\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/owcia.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/owcia.com\/home\/#organization","name":"O\u00f1ate Willy y CIA SC","url":"https:\/\/owcia.com\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/owcia.com\/home\/#\/schema\/logo\/image\/","url":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2017\/10\/logo01.png","contentUrl":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2017\/10\/logo01.png","width":300,"height":126,"caption":"O\u00f1ate Willy y CIA SC"},"image":{"@id":"https:\/\/owcia.com\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/onatewilly\/","https:\/\/x.com\/OWCIAMX","https:\/\/www.instagram.com\/owciamx\/","https:\/\/www.linkedin.com\/company\/owcia"]},{"@type":"Person","@id":"https:\/\/owcia.com\/home\/#\/schema\/person\/888b2ab4896ec57d3727b33389d0d5c9","name":"O\u00f1ate Willy CIA S.C.","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g","caption":"O\u00f1ate Willy CIA S.C."},"url":"https:\/\/owcia.com\/home\/author\/lorenzo\/"}]}},"_links":{"self":[{"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/posts\/2962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/comments?post=2962"}],"version-history":[{"count":0,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/posts\/2962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/media\/2963"}],"wp:attachment":[{"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/media?parent=2962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/categories?post=2962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/tags?post=2962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}