{"id":2856,"date":"2024-06-24T09:46:15","date_gmt":"2024-06-24T15:46:15","guid":{"rendered":"https:\/\/owcia.com\/home\/?p=2856"},"modified":"2024-06-24T09:46:17","modified_gmt":"2024-06-24T15:46:17","slug":"resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china","status":"publish","type":"post","link":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/","title":{"rendered":"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El viernes 21 de junio, la Secretar\u00eda de Econom\u00eda public\u00f3 la resoluci\u00f3n preliminar de la revisi\u00f3n de oficio de la cuota compensatoria impuesta a las importaciones de vajillas y piezas sueltas de vajillas de cer\u00e1mica, incluidas las de porcelana, originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derivado de la investigaci\u00f3n antidumping:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 13 de enero de 2014, se public\u00f3 la \u00abResoluci\u00f3n final de la investigaci\u00f3n antidumping\u00bb, mediante dicha Resoluci\u00f3n, la Secretar\u00eda determin\u00f3 imponer una cuota compensatoria definitiva en los siguientes t\u00e9rminos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">las importaciones de vajillas y piezas sueltas de vajillas de cer\u00e1mica, incluidas las de porcelana, en adelante vajillas, cuyo precio de importaci\u00f3n, correspondiente al valor en aduana de la mercanc\u00eda en t\u00e9rminos unitarios, sea inferior al precio de referencia de 2.61 d\u00f3lares, por kilogramo, estar\u00e1n sujetas al pago de cuotas compensatorias, cuyo monto se calcular\u00e1 como la diferencia entre el precio de importaci\u00f3n y el precio de referencia, sin que se exceda la cuant\u00eda del margen de dumping espec\u00edfico determinado para cada exportador;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">las importaciones de vajillas, originarias de China, cuyo precio de importaci\u00f3n, correspondiente al valor en aduana de la mercanc\u00eda en t\u00e9rminos unitarios, sea igual o superior al precio de referencia de 2.61 d\u00f3lares por kilogramo, no estar\u00e1n sujetas al pago de cuota compensatoria, y<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">se except\u00faa del pago de la cuota compensatoria definitiva a las importaciones de tarros o mugs, siempre y cuando se demuestre lo siguiente:<\/p>\n\n\n\n<ol class=\"wp-block-list\" style=\"list-style-type:upper-roman\">\n<li>Que tienen un recubrimiento de pol\u00edmero\/poli\u00e9ster.<\/li>\n\n\n\n<li>Que no tengan decorado o impresi\u00f3n alguna.<\/li>\n\n\n\n<li>Que ser\u00e1n sometidas a un proceso de impresi\u00f3n por sublimaci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, en sus ex\u00e1menes de vigencia previos se determin\u00f3 lo siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 13 de diciembre de 2019, se public\u00f3 en el DOF la \u00abResoluci\u00f3n final del examen de vigencia de la cuota compensatoria impuesta a las importaciones de vajillas y piezas sueltas de vajillas de cer\u00e1mica, incluidas las de porcelana, originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia\u00bb, mediante la cual la Secretar\u00eda determin\u00f3 mantener la cuota compensatoria por cinco a\u00f1os m\u00e1s, en los t\u00e9rminos descritos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda fij\u00f3 como periodo de la revisi\u00f3n de oficio el comprendido del 1 de enero al 31 de diciembre de 2023 y como periodo de an\u00e1lisis el comprendido del 1 de enero de 2019 al 31 de diciembre de 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presente resoluci\u00f3n dicta lo siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contin\u00faa el procedimiento administrativo de la revisi\u00f3n de oficio de la cuota compensatoria sin modificar la cuota compensatoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se concede un plazo de 20 d\u00edas h\u00e1biles, contados a partir de la publicaci\u00f3n de la presente Resoluci\u00f3n en el DOF, para que las partes interesadas que comparecieron en tiempo y forma en el procedimiento, de considerarlo conveniente, comparezcan ante la Secretar\u00eda para presentar los argumentos y pruebas complementarias que estimen pertinentes. La presente resoluci\u00f3n entrar\u00e1 en vigor al d\u00eda siguiente de su publicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presente resoluci\u00f3n entrar\u00e1 en vigor el d\u00eda siguiente de su publicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a la naturaleza informativa del comunicado, los invitamos a consultar la publicaci\u00f3n oficial en <a href=\"https:\/\/www.dof.gob.mx\/nota_detalle.php?codigo=5731121&amp;fecha=21\/06\/2024#gsc.tab=0\" data-type=\"link\" data-id=\"https:\/\/www.dof.gob.mx\/nota_detalle.php?codigo=5731121&amp;fecha=21\/06\/2024#gsc.tab=0\"><strong>Diario Oficial de la Federaci\u00f3n.<\/strong> <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 21 de junio, la Secretar\u00eda de Econom\u00eda public\u00f3 la resoluci\u00f3n preliminar de la revisi\u00f3n de oficio de la cuota compensatoria impuesta a las importaciones de vajillas y piezas sueltas de vajillas de cer\u00e1mica, incluidas las de porcelana, originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia. Derivado de la investigaci\u00f3n antidumping: [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":2857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"_joinchat":[],"footnotes":""},"categories":[2,1],"tags":[],"class_list":["post-2856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banners","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China &#8226; Agencia Aduanal OWCIA<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China &#8226; Agencia Aduanal OWCIA\" \/>\n<meta property=\"og:description\" content=\"El viernes 21 de junio, la Secretar\u00eda de Econom\u00eda public\u00f3 la resoluci\u00f3n preliminar de la revisi\u00f3n de oficio de la cuota compensatoria impuesta a las importaciones de vajillas y piezas sueltas de vajillas de cer\u00e1mica, incluidas las de porcelana, originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia. Derivado de la investigaci\u00f3n antidumping: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia Aduanal OWCIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/onatewilly\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-24T15:46:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T15:46:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/06\/IMAGENES-BLOG-2024-06-24T094252.610-1024x576.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"O\u00f1ate Willy CIA S.C.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OWCIAMX\" \/>\n<meta name=\"twitter:site\" content=\"@OWCIAMX\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"O\u00f1ate Willy CIA S.C.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/\"},\"author\":{\"name\":\"O\u00f1ate Willy CIA S.C.\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#\\\/schema\\\/person\\\/888b2ab4896ec57d3727b33389d0d5c9\"},\"headline\":\"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China\",\"datePublished\":\"2024-06-24T15:46:15+00:00\",\"dateModified\":\"2024-06-24T15:46:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/\"},\"wordCount\":576,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMAGENES-BLOG-2024-06-24T094252.610.webp\",\"articleSection\":[\"Banners\",\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/\",\"name\":\"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China &#8226; Agencia Aduanal OWCIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMAGENES-BLOG-2024-06-24T094252.610.webp\",\"datePublished\":\"2024-06-24T15:46:15+00:00\",\"dateModified\":\"2024-06-24T15:46:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/#primaryimage\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMAGENES-BLOG-2024-06-24T094252.610.webp\",\"contentUrl\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMAGENES-BLOG-2024-06-24T094252.610.webp\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/owcia.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/\",\"name\":\"Agencia Aduanal OWCIA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/owcia.com\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#organization\",\"name\":\"O\u00f1ate Willy y CIA SC\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/logo01.png\",\"contentUrl\":\"https:\\\/\\\/owcia.com\\\/home\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/logo01.png\",\"width\":300,\"height\":126,\"caption\":\"O\u00f1ate Willy y CIA SC\"},\"image\":{\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/onatewilly\\\/\",\"https:\\\/\\\/x.com\\\/OWCIAMX\",\"https:\\\/\\\/www.instagram.com\\\/owciamx\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/owcia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/owcia.com\\\/home\\\/#\\\/schema\\\/person\\\/888b2ab4896ec57d3727b33389d0d5c9\",\"name\":\"O\u00f1ate Willy CIA S.C.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g\",\"caption\":\"O\u00f1ate Willy CIA S.C.\"},\"url\":\"https:\\\/\\\/owcia.com\\\/home\\\/author\\\/lorenzo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China &#8226; Agencia Aduanal OWCIA","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China &#8226; Agencia Aduanal OWCIA","og_description":"El viernes 21 de junio, la Secretar\u00eda de Econom\u00eda public\u00f3 la resoluci\u00f3n preliminar de la revisi\u00f3n de oficio de la cuota compensatoria impuesta a las importaciones de vajillas y piezas sueltas de vajillas de cer\u00e1mica, incluidas las de porcelana, originarias de la Rep\u00fablica Popular China, independientemente del pa\u00eds de procedencia. Derivado de la investigaci\u00f3n antidumping: [&hellip;]","og_url":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/","og_site_name":"Agencia Aduanal OWCIA","article_publisher":"https:\/\/www.facebook.com\/onatewilly\/","article_published_time":"2024-06-24T15:46:15+00:00","article_modified_time":"2024-06-24T15:46:17+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/06\/IMAGENES-BLOG-2024-06-24T094252.610-1024x576.webp","type":"image\/webp"}],"author":"O\u00f1ate Willy CIA S.C.","twitter_card":"summary_large_image","twitter_creator":"@OWCIAMX","twitter_site":"@OWCIAMX","twitter_misc":{"Escrito por":"O\u00f1ate Willy CIA S.C.","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/#article","isPartOf":{"@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/"},"author":{"name":"O\u00f1ate Willy CIA S.C.","@id":"https:\/\/owcia.com\/home\/#\/schema\/person\/888b2ab4896ec57d3727b33389d0d5c9"},"headline":"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China","datePublished":"2024-06-24T15:46:15+00:00","dateModified":"2024-06-24T15:46:17+00:00","mainEntityOfPage":{"@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/"},"wordCount":576,"commentCount":0,"publisher":{"@id":"https:\/\/owcia.com\/home\/#organization"},"image":{"@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/#primaryimage"},"thumbnailUrl":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/06\/IMAGENES-BLOG-2024-06-24T094252.610.webp","articleSection":["Banners","Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/","url":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/","name":"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China &#8226; Agencia Aduanal OWCIA","isPartOf":{"@id":"https:\/\/owcia.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/#primaryimage"},"image":{"@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/#primaryimage"},"thumbnailUrl":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/06\/IMAGENES-BLOG-2024-06-24T094252.610.webp","datePublished":"2024-06-24T15:46:15+00:00","dateModified":"2024-06-24T15:46:17+00:00","breadcrumb":{"@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/#primaryimage","url":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/06\/IMAGENES-BLOG-2024-06-24T094252.610.webp","contentUrl":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2024\/06\/IMAGENES-BLOG-2024-06-24T094252.610.webp","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/owcia.com\/home\/resolucion-preliminar-para-la-revision-de-la-cuota-compensatoria-a-las-importaciones-de-vajillas-y-piezas-sueltas-de-vajillas-de-ceramica-incluidas-las-de-porcelana-de-china\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/owcia.com\/home\/"},{"@type":"ListItem","position":2,"name":"Resoluci\u00f3n Preliminar Para La Revisi\u00f3n De La Cuota Compensatoria A Las Importaciones De Vajillas Y Piezas Sueltas De Vajillas De Cer\u00e1mica, Incluidas Las De Porcelana De China"}]},{"@type":"WebSite","@id":"https:\/\/owcia.com\/home\/#website","url":"https:\/\/owcia.com\/home\/","name":"Agencia Aduanal OWCIA","description":"","publisher":{"@id":"https:\/\/owcia.com\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/owcia.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/owcia.com\/home\/#organization","name":"O\u00f1ate Willy y CIA SC","url":"https:\/\/owcia.com\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/owcia.com\/home\/#\/schema\/logo\/image\/","url":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2017\/10\/logo01.png","contentUrl":"https:\/\/owcia.com\/home\/wp-content\/uploads\/2017\/10\/logo01.png","width":300,"height":126,"caption":"O\u00f1ate Willy y CIA SC"},"image":{"@id":"https:\/\/owcia.com\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/onatewilly\/","https:\/\/x.com\/OWCIAMX","https:\/\/www.instagram.com\/owciamx\/","https:\/\/www.linkedin.com\/company\/owcia"]},{"@type":"Person","@id":"https:\/\/owcia.com\/home\/#\/schema\/person\/888b2ab4896ec57d3727b33389d0d5c9","name":"O\u00f1ate Willy CIA S.C.","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14b8dc0f59c86c78a01af5463af26d2853f1a51e8a25753cc116e4994b0e5ccf?s=96&d=mm&r=g","caption":"O\u00f1ate Willy CIA S.C."},"url":"https:\/\/owcia.com\/home\/author\/lorenzo\/"}]}},"_links":{"self":[{"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/posts\/2856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/comments?post=2856"}],"version-history":[{"count":0,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/posts\/2856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/media\/2857"}],"wp:attachment":[{"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/media?parent=2856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/categories?post=2856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/owcia.com\/home\/wp-json\/wp\/v2\/tags?post=2856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}